{"id":817,"count":1,"description":"","link":"https:\/\/www.voltage-tester.com\/fr\/tag\/partial-discharge-tester\/","name":"Partial Discharge Tester","slug":"partial-discharge-tester","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Partial Discharge Tester - Run Test Electric Manufacturing Co., Ltd.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.voltage-tester.com\/fr\/tag\/partial-discharge-tester\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partial Discharge Tester - Run Test Electric Manufacturing Co., Ltd.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.voltage-tester.com\/fr\/tag\/partial-discharge-tester\/\" \/>\n<meta property=\"og:site_name\" content=\"Run Test Electric Manufacturing Co., Ltd.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.voltage-tester.com\/wp-content\/uploads\/2025\/03\/20A-High-Voltage-Switch-Dynamic-Characteristics-Circuit-Breaker-Analyser-6.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/\",\"url\":\"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/\",\"name\":\"Partial Discharge Tester - Run Test Electric Manufacturing Co., Ltd.\",\"isPartOf\":{\"@id\":\"https:\/\/www.voltage-tester.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.voltage-tester.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partial Discharge Tester\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.voltage-tester.com\/#website\",\"url\":\"https:\/\/www.voltage-tester.com\/\",\"name\":\"Run Test Electric Manufacturing Co., Ltd.\",\"description\":\"Run Test Electric Manufacturing Co., Ltd.\",\"publisher\":{\"@id\":\"https:\/\/www.voltage-tester.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.voltage-tester.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.voltage-tester.com\/#organization\",\"name\":\"Run Test Electric Manufacturing Co., Ltd.\",\"url\":\"https:\/\/www.voltage-tester.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.voltage-tester.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.voltage-tester.com\/wp-content\/uploads\/2025\/02\/cropped-logo-2-1.png\",\"contentUrl\":\"https:\/\/www.voltage-tester.com\/wp-content\/uploads\/2025\/02\/cropped-logo-2-1.png\",\"width\":264,\"height\":50,\"caption\":\"Run Test Electric Manufacturing Co., Ltd.\"},\"image\":{\"@id\":\"https:\/\/www.voltage-tester.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partial Discharge Tester - Run Test Electric Manufacturing Co., Ltd.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.voltage-tester.com\/fr\/tag\/partial-discharge-tester\/","og_locale":"fr_FR","og_type":"article","og_title":"Partial Discharge Tester - Run Test Electric Manufacturing Co., Ltd.","og_url":"https:\/\/www.voltage-tester.com\/fr\/tag\/partial-discharge-tester\/","og_site_name":"Run Test Electric Manufacturing Co., Ltd.","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.voltage-tester.com\/wp-content\/uploads\/2025\/03\/20A-High-Voltage-Switch-Dynamic-Characteristics-Circuit-Breaker-Analyser-6.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/","url":"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/","name":"Partial Discharge Tester - Run Test Electric Manufacturing Co., Ltd.","isPartOf":{"@id":"https:\/\/www.voltage-tester.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.voltage-tester.com\/tag\/partial-discharge-tester\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.voltage-tester.com\/"},{"@type":"ListItem","position":2,"name":"Partial Discharge Tester"}]},{"@type":"WebSite","@id":"https:\/\/www.voltage-tester.com\/#website","url":"https:\/\/www.voltage-tester.com\/","name":"Run Test Electric Manufacturing Co., Ltd.","description":"Run Test Electric Manufacturing Co., Ltd.","publisher":{"@id":"https:\/\/www.voltage-tester.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.voltage-tester.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.voltage-tester.com\/#organization","name":"Run Test Electric Manufacturing Co., Ltd.","url":"https:\/\/www.voltage-tester.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.voltage-tester.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.voltage-tester.com\/wp-content\/uploads\/2025\/02\/cropped-logo-2-1.png","contentUrl":"https:\/\/www.voltage-tester.com\/wp-content\/uploads\/2025\/02\/cropped-logo-2-1.png","width":264,"height":50,"caption":"Run Test Electric Manufacturing Co., Ltd."},"image":{"@id":"https:\/\/www.voltage-tester.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.voltage-tester.com\/fr\/wp-json\/wp\/v2\/tags\/817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voltage-tester.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.voltage-tester.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.voltage-tester.com\/fr\/wp-json\/wp\/v2\/posts?tags=817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}